{"id":9936,"date":"2022-03-11T00:24:17","date_gmt":"2022-03-11T03:24:17","guid":{"rendered":"https:\/\/cl.abstracta.us\/blog\/?p=9936"},"modified":"2024-02-15T17:15:02","modified_gmt":"2024-02-15T20:15:02","slug":"3-claves-implementacion-exitosa-testing-continuo","status":"publish","type":"post","link":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/","title":{"rendered":"Testing continuo: 3 claves para una implementaci\u00f3n exitosa"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/cl.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo-1024x538.jpg\" alt=\"\" class=\"wp-image-9957\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo-1024x538.jpg 1024w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo-300x158.jpg 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo-768x403.jpg 768w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Pexels<\/em><\/figcaption><\/figure><\/div>\n\n\n<p>A menos que hayas estado sin conexi\u00f3n durante las \u00faltimas d\u00e9cadas, estoy seguro de que ya conoces bien los <strong>beneficios del testing continuo: minimizar los costos del desarrollo, menos desperdicios, mejora de la fiabilidad del sistema y reducci\u00f3n de los riesgos al momento del lanzamiento<\/strong>, entre otros.<\/p>\n\n\n\n<p>Sin embargo, ponerlo en pr\u00e1ctica en el mundo real no es tan sencillo como algunas compa\u00f1\u00edas pueden hacerte creer. Es claro que el hecho de tener configurada una herramienta de integraci\u00f3n continua no significa que un equipo logre implementar con \u00e9xito las pruebas continuas.<\/p>\n\n\n\n<p>Afortunadamente, ahora tenemos m\u00e1s recursos que nunca para superar este reto organizativo, como el ACT framework. Hace un tiempo, mi equipo y yo publicamos nuestra <a href=\"https:\/\/cl.abstracta.us\/guia-testing-continuo\" target=\"_blank\" rel=\"noreferrer noopener\">Gu\u00eda de Testing Continuo<\/a>, que est\u00e1 alineada con la filosof\u00eda del <a href=\"https:\/\/www.tricentis.com\/transformation\/framework\/\" target=\"_blank\" rel=\"noreferrer noopener\">ACT framework<\/a>.<\/p>\n\n\n\n<p>En este art\u00edculo, voy a compartir algunas consideraciones clave y consejos de esta gu\u00eda con el fin lograr una <strong>implementaci\u00f3n exitosa de testing continuo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Evaluar tu equipo actual, la tecnolog\u00eda y los procesos<\/strong><\/h2>\n\n\n\n<p>Siempre que se busque mejorar los resultados del desarrollo de software, es necesario tener en cuenta tres pilares fundamentales que est\u00e1n estrechamente relacionados entre s\u00ed: los procesos, las herramientas y las personas.<\/p>\n\n\n\n<p>Los equipos pueden aprender continuamente y mejorar sus procesos, pero las herramientas que utilizan y los propios miembros del equipo tambi\u00e9n deben adaptarse para que los nuevos y mejorados procesos tengan \u00e9xito a largo plazo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1000\" src=\"https:\/\/cl.abstracta.us\/wp-content\/uploads\/2022\/06\/pilares-clave-madurez-testing-software-personas-tecnologia-procesos-1024x1000.png\" alt=\"3 pilares clave en el testing y desarrollo de software: personas, tecnolog\u00eda y procesos\" class=\"wp-image-11778\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/pilares-clave-madurez-testing-software-personas-tecnologia-procesos-1024x1000.png 1024w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/pilares-clave-madurez-testing-software-personas-tecnologia-procesos-300x293.png 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/pilares-clave-madurez-testing-software-personas-tecnologia-procesos-768x750.png 768w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/pilares-clave-madurez-testing-software-personas-tecnologia-procesos-1536x1500.png 1536w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/pilares-clave-madurez-testing-software-personas-tecnologia-procesos-2048x2000.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<h4 class=\"wp-block-heading\">Algunas de las preguntas que recomiendo hacer aqu\u00ed:<\/h4>\n\n\n\n<p>\u25cf \u00bfTenemos una idea com\u00fan de nuestro delivery pipeline? No pienses solo en el proceso de desarrollo, sino tambi\u00e9n en la forma de aportar valor a tu empresa.<br>\u25cf \u00bfCu\u00e1nto de esto est\u00e1 automatizado? \u00bfTenemos un motor de CI\/CD instalado?<br>\u25cf \u00bfNuestras herramientas y procesos de testing actuales se integran con estos pipelines?<br>\u25cf \u00bfNos falta experiencia para automatizar? \u00bfDebemos invertir en formaci\u00f3n? Si as\u00ed es, \u00bfen qu\u00e9?<br>\u25cf \u00bfCu\u00e1les son nuestras mayores limitaciones? \u00bfTiempo, presupuesto y\/o recursos? \u00bfC\u00f3mo podemos compensar alguna de estas?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Saber cu\u00e1les son los factores de calidad m\u00e1s importantes<\/strong><\/h2>\n\n\n\n<p>Para cada equipo, algunos factores de calidad ser\u00e1n m\u00e1s importantes que otros, por lo que no siempre es necesario o inteligente centrarse en las pruebas continuas para cada factor de calidad del software.<\/p>\n\n\n\n<p>Por ejemplo, si est\u00e1s trabajando en un sistema para un grupo de usuarios muy diverso, las <a href=\"https:\/\/cl.abstracta.us\/blog\/pruebas-usabilidad-desde-mirada-testing\/\" target=\"_blank\" rel=\"noreferrer noopener\">pruebas de usabilidad<\/a> pueden ser m\u00e1s prioritarias que las <a href=\"https:\/\/cl.abstracta.us\/blog\/pruebas-de-performance\/\" target=\"_blank\" rel=\"noreferrer noopener\">pruebas de performance<\/a>. Por ejemplo, un sistema gubernamental utilizado por los ciudadanos para presentar sus impuestos puede requerir un mayor grado de usabilidad y seguridad que de performance.<\/p>\n\n\n\n<p>Seg\u00fan las <a href=\"https:\/\/cl.abstracta.us\/blog\/software-testing-wheel\/\" target=\"_blank\" rel=\"noreferrer noopener\">normas ISO 25010<\/a> para la calidad de los productos de software, hay ocho caracter\u00edsticas de calidad del software: idoneidad funcional, eficiencia de rendimiento, compatibilidad, usabilidad, fiabilidad, seguridad, mantenibilidad y portabilidad. Para cada una de ellas, tienes el correspondiente conjunto de pruebas para evaluar su nivel de calidad.<\/p>\n\n\n\n<p>Recomiendo que tengas una instancia de evaluaci\u00f3n junto a tu equipo, para identificar cu\u00e1les son las mayores \u00e1reas de preocupaci\u00f3n respecto a la calidad del software para los usuarios y las partes interesadas.<\/p>\n\n\n\n<p>\u00bfCu\u00e1les son los peores escenarios en los que, si algo se \u201crompiera\u201d, causar\u00eda el mayor da\u00f1o? \u00c9stos son los riesgos que deben abordarse en primer lugar. Seguir un enfoque basado en riesgos por un determinado tiempo entre versi\u00f3n y versi\u00f3n, ya sean horas, d\u00edas o semanas, ser\u00e1 de gran ayuda para identificar qu\u00e9 conviene priorizar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Trazar tu ruta hacia el testing continuo<\/strong><\/h2>\n\n\n\n<p>Hay varias \u00e1reas de calidad que van a resultar de gran ayuda en tus esfuerzos para alcanzar un programa de testing continuo eficiente, abarcando <a href=\"https:\/\/cl.abstracta.us\/blog\/beneficios-enfoque-shift-left-testing\/\" target=\"_blank\" rel=\"noreferrer noopener\">shift-left testing<\/a> y shift-right testing.<\/p>\n\n\n\n<p>El siguiente modelo describe los <strong>tres niveles de madurez de testing: b\u00e1sico, eficiente y continuo<\/strong>. En este se puede visualizar c\u00f3mo la gesti\u00f3n de los diferentes aspectos de la calidad del c\u00f3digo fuente, los ambientes y la automatizaci\u00f3n de las pruebas, entre otros, deben establecerse para implementar el testing continuo. Por ejemplo, antes de tener el motor de CI\/CD instalado, hay que implementar el versionado del c\u00f3digo fuente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"617\" src=\"https:\/\/cl.abstracta.us\/wp-content\/uploads\/2022\/06\/niveles-madurez-testing-software-1024x617.png\" alt=\"Niveles de madurez de testing de software: b\u00e1sico, eficiente y continuo\" class=\"wp-image-11781\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/niveles-madurez-testing-software-1024x617.png 1024w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/niveles-madurez-testing-software-300x181.png 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/niveles-madurez-testing-software-768x463.png 768w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/06\/niveles-madurez-testing-software.png 1439w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>Sugiero que utilices este modelo como referencia para revisar la situaci\u00f3n de tu equipo respecto a las nueve \u00e1reas de calidad. Revisa las filas de arriba a abajo, considera junto a los miembros de tu equipo si est\u00e1n manejando cada \u00e1rea mencionada de tal manera que se caracterice por pruebas b\u00e1sicas, eficientes o continuas.<\/p>\n\n\n\n<p>A partir de ah\u00ed, se puede elaborar un plan de acci\u00f3n para avanzar en estos niveles de madurez, hasta alcanzar el nivel de testing continuo. Aborda las \u00e1reas que deben mejorarse primero, es decir, las m\u00e1s cr\u00edticas que sustentan los siguientes pasos hacia la implementaci\u00f3n de pruebas continuas, y tambi\u00e9n las caracter\u00edsticas de la calidad del software que tu equipo ha determinado como m\u00e1s cr\u00edticas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prepararse para el \u00e9xito<\/h2>\n\n\n\n<p>Como dice el viejo refr\u00e1n, \u201cno planificar es planear el fracaso\u201d. Antes de entusiasmarse con las pruebas continuas, automatizando todo lo que es apto de ser automatizable, es recomendable primero tener las cosas claras sobre c\u00f3mo imaginamos el \u00e9xito que queremos alcanzar, dado el contexto de tu equipo y los objetivos del negocio. No te preocupes si tu equipo comete algunos errores en el camino, siempre y cuando est\u00e9 dispuesto a aprender y mejorar sobre la marcha.<\/p>\n\n\n\n<p>Recuerda que, en primer lugar, debes comprender los objetivos de tu organizaci\u00f3n, as\u00ed como tu equipo, procesos y herramientas. Conoce los riesgos que son m\u00e1s importantes de mitigar con el testing continuo y construye un plan de acci\u00f3n concreto y realista a partir de ah\u00ed.<\/p>\n\n\n\n<p>\u00a1S\u00edguenos en&nbsp;<a href=\"https:\/\/bit.ly\/LinkedIn-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>,&nbsp;<a href=\"https:\/\/bit.ly\/TW-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a>,&nbsp;<a href=\"https:\/\/bit.ly\/FB-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>,&nbsp;<a href=\"https:\/\/bit.ly\/Instagram-Abstracta-Latam\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/bit.ly\/YT-Abstracta\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>&nbsp;para ser parte de nuestra comunidad y enterarte de otras buenas pr\u00e1cticas para implementar pruebas continuas!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide\" style=\"background-color:#f1f1f1;color:#f1f1f1\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Otros contenidos relacionados<\/h3>\n\n\n\n<p><a href=\"https:\/\/cl.abstracta.us\/blog\/guia-crear-estrategia-pruebas-software-adecuada\/\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3mo crear la estrategia de pruebas adecuada para tu proyecto<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/cl.abstracta.us\/blog\/testing-agil-productos-digitales-calidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">Testing \u00c1gil para crear productos digitales de alta Calidad<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/cl.abstracta.us\/blog\/elementos-clave-lanzamiento-productos-digitales-calidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">3 elementos esenciales para lanzar Software r\u00e1pidamente, sin afectar la Calidad<\/a><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.<\/p>\n","protected":false},"author":9,"featured_media":9965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,60],"tags":[3,120,89,61,2,63,164,167],"class_list":["post-9936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calidad-software","category-testing-agil","tag-automatizacion-pruebas","tag-pruebas-performance","tag-pruebas-de-seguridad","tag-pruebas-de-usabilidad","tag-pruebas-funcionales","tag-shift-left-testing","tag-shift-right-testing","tag-testing-continuo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Testing continuo: 3 claves para una implementaci\u00f3n exitosa - Abstracta<\/title>\n<meta name=\"description\" content=\"Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testing continuo: 3 claves para una implementaci\u00f3n exitosa - Abstracta\" \/>\n<meta property=\"og:description\" content=\"Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AbstractaChile\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T03:24:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T20:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federico Toledo, Chief Quality Officer en Abstracta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fltoledo\" \/>\n<meta name=\"twitter:site\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Toledo, Chief Quality Officer en Abstracta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\"},\"author\":{\"name\":\"Federico Toledo, Chief Quality Officer en Abstracta\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/394e6ba8f90dc5b3c2bd05887419a4af\"},\"headline\":\"Testing continuo: 3 claves para una implementaci\u00f3n exitosa\",\"datePublished\":\"2022-03-11T03:24:17+00:00\",\"dateModified\":\"2024-02-15T20:15:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\"},\"wordCount\":1036,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"keywords\":[\"Automatizaci\u00f3n de Pruebas\",\"Pruebas de Performance\",\"Pruebas de Seguridad\",\"Pruebas de Usabilidad\",\"Pruebas Funcionales\",\"Shift Left Testing\",\"Shift Right Testing\",\"Testing Continuo\"],\"articleSection\":[\"Calidad de Software\",\"Testing \u00c1gil\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\",\"url\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\",\"name\":\"Testing continuo: 3 claves para una implementaci\u00f3n exitosa - Abstracta\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\"},\"datePublished\":\"2022-03-11T03:24:17+00:00\",\"dateModified\":\"2024-02-15T20:15:02+00:00\",\"description\":\"Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.\",\"breadcrumb\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/es.abstracta.us\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testing continuo: 3 claves para una implementaci\u00f3n exitosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"name\":\"Abstracta\",\"description\":\"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.\",\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\",\"name\":\"Abstracta\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"contentUrl\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"width\":1217,\"height\":300,\"caption\":\"Abstracta\"},\"image\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/we_are_abstracta\/\",\"https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/\",\"https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ\",\"https:\/\/www.facebook.com\/AbstractaChile\/\",\"https:\/\/twitter.com\/AbstractaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/394e6ba8f90dc5b3c2bd05887419a4af\",\"name\":\"Federico Toledo, Chief Quality Officer en Abstracta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5a791bcef3d344e8a3a4e95c143fa27c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5a791bcef3d344e8a3a4e95c143fa27c?s=96&d=mm&r=g\",\"caption\":\"Federico Toledo, Chief Quality Officer en Abstracta\"},\"description\":\"Chief Quality Officer en Abstracta\",\"sameAs\":[\"http:\/\/cl.abstracta.us\",\"https:\/\/www.linkedin.com\/in\/federicotoledo\/\",\"https:\/\/twitter.com\/fltoledo\"],\"url\":\"https:\/\/es.abstracta.us\/blog\/author\/federico-toledo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Testing continuo: 3 claves para una implementaci\u00f3n exitosa - Abstracta","description":"Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/","og_locale":"es_ES","og_type":"article","og_title":"Testing continuo: 3 claves para una implementaci\u00f3n exitosa - Abstracta","og_description":"Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.","og_url":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/","og_site_name":"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta","article_publisher":"https:\/\/www.facebook.com\/AbstractaChile\/","article_published_time":"2022-03-11T03:24:17+00:00","article_modified_time":"2024-02-15T20:15:02+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo-1024x576.png","type":"image\/png"}],"author":"Federico Toledo, Chief Quality Officer en Abstracta","twitter_card":"summary_large_image","twitter_creator":"@fltoledo","twitter_site":"@AbstractaChile","twitter_misc":{"Written by":"Federico Toledo, Chief Quality Officer en Abstracta","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#article","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/"},"author":{"name":"Federico Toledo, Chief Quality Officer en Abstracta","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/394e6ba8f90dc5b3c2bd05887419a4af"},"headline":"Testing continuo: 3 claves para una implementaci\u00f3n exitosa","datePublished":"2022-03-11T03:24:17+00:00","dateModified":"2024-02-15T20:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/"},"wordCount":1036,"commentCount":0,"publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"keywords":["Automatizaci\u00f3n de Pruebas","Pruebas de Performance","Pruebas de Seguridad","Pruebas de Usabilidad","Pruebas Funcionales","Shift Left Testing","Shift Right Testing","Testing Continuo"],"articleSection":["Calidad de Software","Testing \u00c1gil"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/","url":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/","name":"Testing continuo: 3 claves para una implementaci\u00f3n exitosa - Abstracta","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/#website"},"datePublished":"2022-03-11T03:24:17+00:00","dateModified":"2024-02-15T20:15:02+00:00","description":"Consideraciones para elaborar un plan de acci\u00f3n que permita avanzar en los niveles de madurez, hasta lograr una implementaci\u00f3n exitosa de testing continuo.","breadcrumb":{"@id":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/es.abstracta.us\/blog\/3-claves-implementacion-exitosa-testing-continuo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.abstracta.us\/blog\/"},{"@type":"ListItem","position":2,"name":"Testing continuo: 3 claves para una implementaci\u00f3n exitosa"}]},{"@type":"WebSite","@id":"https:\/\/es.abstracta.us\/blog\/#website","url":"https:\/\/es.abstracta.us\/blog\/","name":"Abstracta","description":"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.","publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/es.abstracta.us\/blog\/#organization","name":"Abstracta","url":"https:\/\/es.abstracta.us\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","contentUrl":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","width":1217,"height":300,"caption":"Abstracta"},"image":{"@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/we_are_abstracta\/","https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/","https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ","https:\/\/www.facebook.com\/AbstractaChile\/","https:\/\/twitter.com\/AbstractaChile"]},{"@type":"Person","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/394e6ba8f90dc5b3c2bd05887419a4af","name":"Federico Toledo, Chief Quality Officer en Abstracta","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5a791bcef3d344e8a3a4e95c143fa27c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a791bcef3d344e8a3a4e95c143fa27c?s=96&d=mm&r=g","caption":"Federico Toledo, Chief Quality Officer en Abstracta"},"description":"Chief Quality Officer en Abstracta","sameAs":["http:\/\/cl.abstracta.us","https:\/\/www.linkedin.com\/in\/federicotoledo\/","https:\/\/twitter.com\/fltoledo"],"url":"https:\/\/es.abstracta.us\/blog\/author\/federico-toledo\/"}]}},"jetpack_featured_media_url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2022\/03\/3-claves-implementacion-exitosa-testing-continuo.png","_links":{"self":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/9936"}],"collection":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/comments?post=9936"}],"version-history":[{"count":22,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/9936\/revisions"}],"predecessor-version":[{"id":17070,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/9936\/revisions\/17070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media\/9965"}],"wp:attachment":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media?parent=9936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/categories?post=9936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/tags?post=9936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}