{"id":3595,"date":"2020-11-06T21:40:46","date_gmt":"2020-11-07T00:40:46","guid":{"rendered":"http:\/\/cl.abstracta.us\/blog\/?p=3595"},"modified":"2024-02-15T17:30:04","modified_gmt":"2024-02-15T20:30:04","slug":"world-quality-report-2021","status":"publish","type":"post","link":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/","title":{"rendered":"World Quality Report 2021: Lo m\u00e1s destacado"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Compa\u00f1\u00edas dan prioridad a la calidad para impulsar transformaci\u00f3n digital empresarial.<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/cl.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021-300x300.png\" alt=\"\" class=\"wp-image-3639\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021-300x300.png 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021-150x150.png 150w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021.png 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n<p>World Quality Report 2021\u2014 o por sus siglas en ingl\u00e9s WQR &#8211; destaca, en primer lugar, que el QA ha tenido una constante evoluci\u00f3n: Pas\u00f3 de ser una actividad independiente dentro de las compa\u00f1\u00edas, a convertirse en una funci\u00f3n totalmente integrada del equipo y del ciclo de vida de desarrollo, mientras aumentan los esfuerzos en materia de transformaci\u00f3n digital.<\/p>\n\n\n\n<p>Para este a\u00f1o, la pandemia ha acelerado la transformaci\u00f3n digital en muchos sectores. La combinaci\u00f3n de un presupuesto de TI reducido y un cambio de enfoque hacia lo digital, est\u00e1 impulsando a las organizaciones a innovar y ser m\u00e1s eficientes.<\/p>\n\n\n\n<p><strong>El WQR es el \u00fanico informe global que analiza la calidad y las tendencias respecto al testing de software.<\/strong> Veamos a continuaci\u00f3n cu\u00e1les son los aspectos m\u00e1s relevantes del reporte de este a\u00f1o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">QA, parte integral de la transformaci\u00f3n digital<\/h2>\n\n\n\n<p>La edici\u00f3n n\u00b0. 12 de este informe publicado por <a href=\"https:\/\/www.capgemini.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abrir en una nueva pesta\u00f1a)\">Capgemini<\/a> , <a rel=\"noreferrer noopener\" aria-label=\" (abrir en una nueva pesta\u00f1a)\" href=\"https:\/\/www.sogeti.com\/\" target=\"_blank\">Sogeti<\/a> y <a rel=\"noreferrer noopener\" aria-label=\" (abrir en una nueva pesta\u00f1a)\" href=\"https:\/\/www.microfocus.com\/en-us\/home\" target=\"_blank\">Micro Focus<\/a> se\u00f1ala que QA es una parte integral de la transformaci\u00f3n digital, para poder impulsar tanto el crecimiento empresarial, como la satisfacci\u00f3n del usuario final.<\/p>\n\n\n\n<p>Con 1.750 CIO  y profesionales de TI de alto rango entrevistados (Directores de TI, QA Managers, CDO, CMO, CTO, Product Manager) de 10 sectores diferentes en 32 pa\u00edses, el Informe muestra que el &#8216;Business Assurance&#8217; es el objetivo de QA y testing m\u00e1s importante.<\/p>\n\n\n\n<p>Por otro lado, los profesionales de control de calidad ya no son los \u00fanicos responsables del testing y de encontrar bugs. En la actualidad, deben enfocar sus esfuerzos para asegurar que el resto del equipo se involucre con dichas actividades, seg\u00fan el \u00faltimo WQR.<\/p>\n\n\n\n<p>Sin embargo, a los equipos de control de calidad se les ha solicitado que hagan mucho m\u00e1s con mucho menos. Esto los ha forzado a innovar, ser m\u00e1s eficientes y a adaptarse a nuevas formas de trabajar a consecuencia de la pandemia global.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Adopci\u00f3n de Agile y DevOps aumenta pero persisten los desaf\u00edos<\/h2>\n\n\n\n<p>Al igual que en las dos \u00faltimas ediciones, este a\u00f1o hubo un aumento significativo en la adopci\u00f3n de las metodolog\u00edas Agile y DevOps.&nbsp;Si bien hay un claro enfoque en aumentar las pruebas automatizadas y un cambio a <a href=\"https:\/\/www.federico-toledo.com\/que-es-shift-left-testing\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abrir en una nueva pesta\u00f1a)\">Shift Left Testing<\/a> &#8211; una pr\u00e1ctica destinada a encontrar y prevenir bugs en las primeras etapas del proceso de desarrollo del software &#8211; utilizando Agile y DevOps, sigue siendo un desaf\u00edo alcanzar un nivel mayor de automatizaci\u00f3n, y contar con conocimiento especializado dentro del equipo de QA.<\/p>\n\n\n\n<p><strong>El World Quality Report 2021 se\u00f1ala que se est\u00e1 impulsando el control de calidad, para que est\u00e9 a\u00fan m\u00e1s conectado con las necesidades del negocio.  <\/strong><\/p>\n\n\n\n<p>A medida que aumenta la complejidad del desarrollo de software, los equipos de control de calidad est\u00e1n m\u00e1s comprometidos para mantener la calidad en una amplia gama de atributos (funcional, performance, seguridad, usabilidad, etc..). Asimismo, se est\u00e1n convirtiendo en los articuladores de la calidad dentro de las compa\u00f1\u00edas..<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Altas expectativas sobre los beneficios de Inteligencia Artificial<\/h2>\n\n\n\n<p>Gran parte de los encuestados se encuentran entusiasmados con las posibilidades que brinda la inteligencia artificial: Casi un 90% afirma que las pruebas con IA y las pruebas de IA son las mayores \u00e1reas de crecimiento dentro de sus compa\u00f1\u00edas. Y un 80% manifest\u00f3 su intenci\u00f3n de aumentar el n\u00famero de ensayos y pruebas de concepto basados \u200b\u200ben IA.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/cl.abstracta.us\/wp-content\/uploads\/2020\/11\/inteligencia-artificial-world-quality-report-21-1024x564.png\" alt=\"Gr\u00e1fica 1: \u00bfEn qu\u00e9 medida las siguientes declaraciones reflejan sus planes para utilizar la IA en las actividades QA? - Fuente: WQR 20-21\" class=\"wp-image-3612\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/inteligencia-artificial-world-quality-report-21-1024x564.png 1024w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/inteligencia-artificial-world-quality-report-21-300x165.png 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/inteligencia-artificial-world-quality-report-21-768x423.png 768w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/inteligencia-artificial-world-quality-report-21.png 1064w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Gr\u00e1fica 1: \u00bfEn qu\u00e9 medida las siguientes declaraciones reflejan sus planes para utilizar la IA en las actividades QA? &#8211; Fuente: WQR 20-21<\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Automatizaci\u00f3n de Pruebas: Mayor control de actividades de QA<\/h2>\n\n\n\n<p>Informes de Calidad anteriores han se\u00f1alado constantes desaf\u00edos en el \u00e1rea de la automatizaci\u00f3n de pruebas. De hecho, en 2019 se destac\u00f3 la falta de ingenieros con conocimientos especializados y una experiencia consolidada.<\/p>\n\n\n\n<p>En 2020, los encuestados expresaron cierto grado de confianza respecto a la automatizaci\u00f3n de pruebas: un 68% se\u00f1al\u00f3 que cuenta con el conjunto de herramientas de automatizaci\u00f3n necesarias; mientras que un 63% cuenta con suficiente tiempo para crear y mantener pruebas automatizadas.<\/p>\n\n\n\n<p>Solo un 18% est\u00e1 automatizando sus pruebas de validaci\u00f3n y pruebas unitarias. Si bien esto representa un aumento del 3% con respecto al 2019, la tasa general de automatizaci\u00f3n de pruebas de un 15%, deja un margen considerable para mejorar.<\/p>\n\n\n\n<p><strong>El World Quality Report 2021 pone en evidencia m\u00e1s beneficios de la automatizaci\u00f3n de pruebas, tales como: mejor control y transparencia de las actividades de testing, y una reducci\u00f3n en el tiempo del ciclo de pruebas.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pandemia y QA: Normalizaci\u00f3n del trabajo remoto<\/h2>\n\n\n\n<p>Si bien la pandemia de coronavirus ha representado un gran desaf\u00edo para las compa\u00f1\u00edas &#8211; especialmente las que a\u00fan no se hab\u00edan subido a la nube &#8211; tambi\u00e9n ha actuado como un acelerador: motivando a las organizaciones y equipos a hacer m\u00e1s cosas y hacerlas mejor. De este modo, haciendo imprescindibles las herramientas de comunicaci\u00f3n y colaboraci\u00f3n, para coordinar y dar m\u00e1s visibilidad de las actividades de QA.<\/p>\n\n\n\n<p><strong>Un 17% de los encuestados del World Quality Report 2021 afirmaron que se centrar\u00e1n significativamente en validar la experiencia del cliente y en las pruebas de usabilidad.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/cl.abstracta.us\/wp-content\/uploads\/2020\/11\/experiencia-cliente-pruebas-usabilidad-world-quality-report-21-1024x684.png\" alt=\"Enfoque en la experiencia del cliente y en las pruebas de usabilidad - World Quality Report 2021\" class=\"wp-image-3627\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/experiencia-cliente-pruebas-usabilidad-world-quality-report-21-1024x684.png 1024w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/experiencia-cliente-pruebas-usabilidad-world-quality-report-21-300x200.png 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/experiencia-cliente-pruebas-usabilidad-world-quality-report-21-768x513.png 768w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/experiencia-cliente-pruebas-usabilidad-world-quality-report-21.png 1064w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Gr\u00e1fica 2: \u00bfC\u00f3mo ha cambiado su enfoque respecto a las actividades de QA para afrontar los desaf\u00edos causados por la pandemia? &#8211; WQR 2021<\/figcaption><\/figure><\/div>\n\n\n<p>Por otro lado, con la r\u00e1pida adopci\u00f3n del trabajo remoto, han aumentado los casos de ciberataques; por tanto, un 83% de los CIO y profesionales de TI encuestados mostraron su preocupaci\u00f3n por la seguridad de sus sistemas en los \u00faltimos meses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo deben prepararse los equipos de QA?\u00a0<\/strong><\/h2>\n\n\n\n<p>La transformaci\u00f3n digital requiere un control de calidad eficaz. La pandemia global ha impulsado a las organizaciones para que aceleren sus iniciativas de transformaci\u00f3n digital, lo que ha aumenta el esfuerzo a\u00fan m\u00e1s para los equipos.<\/p>\n\n\n\n<p>El resultado es que las organizaciones est\u00e1n reevaluando su enfoque de QA, aumentando su adopci\u00f3n de infraestructuras <em>cloud<\/em> y poniendo mayor \u00e9nfasis en la seguridad.<\/p>\n\n\n\n<p>Estas son las principales recomendaciones para los equipos de QA, seg\u00fan el World Quality Report 2021:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong> La calidad es asunto de todos, no solo de los ingenieros de QA<\/strong>: Se debe compartir la responsabilidad de la calidad en todo el equipo.<\/li>\n\n\n\n<li><strong>Mejorar las habilidades y adoptar herramientas avanzadas<\/strong>: Aprovechar herramientas m\u00e1s inteligentes&nbsp;que incluyan inteligencia artificial, machine learning y an\u00e1lisis.<\/li>\n\n\n\n<li><strong>Optimizar la inversi\u00f3n en infraestructura<\/strong>.<\/li>\n\n\n\n<li><strong>Implementar un plan de continuidad empresarial s\u00f3lido<\/strong>, para evitar que ocurran incidentes, y estar preparado para responder r\u00e1pidamente ante cualquier novedad.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.<\/p>\n","protected":false},"author":4,"featured_media":3660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119],"tags":[221,3,184,111,133,140,42],"class_list":["post-3595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calidad-software","tag-agilidad","tag-automatizacion-pruebas","tag-devops","tag-inteligencia-artificial","tag-qa","tag-quality-assurance","tag-world-quality-report"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>World Quality Report 2021: Lo m\u00e1s destacado - Abstracta<\/title>\n<meta name=\"description\" content=\"World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"World Quality Report 2021: Lo m\u00e1s destacado - Abstracta\" \/>\n<meta property=\"og:description\" content=\"World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AbstractaChile\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-07T00:40:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T20:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julieth Soler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:site\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieth Soler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\"},\"author\":{\"name\":\"Julieth Soler\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/547fd27b2ff2c9c9ff2a6189bda7026d\"},\"headline\":\"World Quality Report 2021: Lo m\u00e1s destacado\",\"datePublished\":\"2020-11-07T00:40:46+00:00\",\"dateModified\":\"2024-02-15T20:30:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\"},\"wordCount\":1129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"keywords\":[\"Agilidad\",\"Automatizaci\u00f3n de Pruebas\",\"DevOps\",\"Inteligencia Artificial\",\"QA\",\"Quality Assurance\",\"World Quality Report\"],\"articleSection\":[\"Calidad de Software\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\",\"url\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\",\"name\":\"World Quality Report 2021: Lo m\u00e1s destacado - Abstracta\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\"},\"datePublished\":\"2020-11-07T00:40:46+00:00\",\"dateModified\":\"2024-02-15T20:30:04+00:00\",\"description\":\"World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.\",\"breadcrumb\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/es.abstracta.us\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"World Quality Report 2021: Lo m\u00e1s destacado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"name\":\"Abstracta\",\"description\":\"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.\",\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\",\"name\":\"Abstracta\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"contentUrl\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"width\":1217,\"height\":300,\"caption\":\"Abstracta\"},\"image\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/we_are_abstracta\/\",\"https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/\",\"https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ\",\"https:\/\/www.facebook.com\/AbstractaChile\/\",\"https:\/\/twitter.com\/AbstractaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/547fd27b2ff2c9c9ff2a6189bda7026d\",\"name\":\"Julieth Soler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5a5c0db120e17cef9ba4de39aa183ed2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5a5c0db120e17cef9ba4de39aa183ed2?s=96&d=mm&r=g\",\"caption\":\"Julieth Soler\"},\"description\":\"Digital Marketing Manager en Abstracta Chile\",\"sameAs\":[\"https:\/\/cl.abstracta.us\/\",\"https:\/\/www.linkedin.com\/in\/juliethsoler\/\"],\"url\":\"https:\/\/es.abstracta.us\/blog\/author\/julieth\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"World Quality Report 2021: Lo m\u00e1s destacado - Abstracta","description":"World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/","og_locale":"es_ES","og_type":"article","og_title":"World Quality Report 2021: Lo m\u00e1s destacado - Abstracta","og_description":"World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.","og_url":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/","og_site_name":"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta","article_publisher":"https:\/\/www.facebook.com\/AbstractaChile\/","article_published_time":"2020-11-07T00:40:46+00:00","article_modified_time":"2024-02-15T20:30:04+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021-1.png","type":"image\/png"}],"author":"Julieth Soler","twitter_card":"summary_large_image","twitter_creator":"@AbstractaChile","twitter_site":"@AbstractaChile","twitter_misc":{"Written by":"Julieth Soler","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#article","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/"},"author":{"name":"Julieth Soler","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/547fd27b2ff2c9c9ff2a6189bda7026d"},"headline":"World Quality Report 2021: Lo m\u00e1s destacado","datePublished":"2020-11-07T00:40:46+00:00","dateModified":"2024-02-15T20:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/"},"wordCount":1129,"commentCount":0,"publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"keywords":["Agilidad","Automatizaci\u00f3n de Pruebas","DevOps","Inteligencia Artificial","QA","Quality Assurance","World Quality Report"],"articleSection":["Calidad de Software"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/","url":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/","name":"World Quality Report 2021: Lo m\u00e1s destacado - Abstracta","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/#website"},"datePublished":"2020-11-07T00:40:46+00:00","dateModified":"2024-02-15T20:30:04+00:00","description":"World Quality Report 2021 destaca QA como parte integral de la transformaci\u00f3n digital, que impulsa el crecimiento empresarial y la satisfacci\u00f3n del usuario.","breadcrumb":{"@id":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/es.abstracta.us\/blog\/world-quality-report-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.abstracta.us\/blog\/"},{"@type":"ListItem","position":2,"name":"World Quality Report 2021: Lo m\u00e1s destacado"}]},{"@type":"WebSite","@id":"https:\/\/es.abstracta.us\/blog\/#website","url":"https:\/\/es.abstracta.us\/blog\/","name":"Abstracta","description":"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.","publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/es.abstracta.us\/blog\/#organization","name":"Abstracta","url":"https:\/\/es.abstracta.us\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","contentUrl":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","width":1217,"height":300,"caption":"Abstracta"},"image":{"@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/we_are_abstracta\/","https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/","https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ","https:\/\/www.facebook.com\/AbstractaChile\/","https:\/\/twitter.com\/AbstractaChile"]},{"@type":"Person","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/547fd27b2ff2c9c9ff2a6189bda7026d","name":"Julieth Soler","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5a5c0db120e17cef9ba4de39aa183ed2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a5c0db120e17cef9ba4de39aa183ed2?s=96&d=mm&r=g","caption":"Julieth Soler"},"description":"Digital Marketing Manager en Abstracta Chile","sameAs":["https:\/\/cl.abstracta.us\/","https:\/\/www.linkedin.com\/in\/juliethsoler\/"],"url":"https:\/\/es.abstracta.us\/blog\/author\/julieth\/"}]}},"jetpack_featured_media_url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2020\/11\/world-quality-report-2021-1.png","_links":{"self":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/3595"}],"collection":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/comments?post=3595"}],"version-history":[{"count":88,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/3595\/revisions"}],"predecessor-version":[{"id":17108,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/3595\/revisions\/17108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media\/3660"}],"wp:attachment":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media?parent=3595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/categories?post=3595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/tags?post=3595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}