{"id":17795,"date":"2023-02-03T11:16:00","date_gmt":"2023-02-03T14:16:00","guid":{"rendered":"https:\/\/es.abstracta.us\/blog\/?p=17795"},"modified":"2024-05-15T14:56:00","modified_gmt":"2024-05-15T18:56:00","slug":"nuevos-chief-operations-quality-officer-abstracta","status":"publish","type":"post","link":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/","title":{"rendered":"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.linkedin.com\/in\/alejandra-viglietti-3a7a161b\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alejandra Viglietti<\/a>, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de&nbsp;<a href=\"https:\/\/www.linkedin.com\/in\/federicotoledo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Federico Toledo<\/a>, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/miro.medium.com\/v2\/resize:fit:630\/0*Ht5KIrn3tCJIN4nI\" alt=\"\"\/><\/figure><\/div>\n\n\n<p id=\"4181\"><strong>Operations, Sustainability, Growth, Innovation, Culture y Marketing son las \u00e1reas que componen Abstracta, empresa l\u00edder mundial en testing de software con casi 15 a\u00f1os de experiencia y sedes en Am\u00e9rica del Norte, Am\u00e9rica Latina y Europa. En 2023, creamos el rol de Chief Quality Officer, asumido por Federico Toledo, y sumamos una nueva integrante a nuestro C-Suite: Alejandra Viglietti, como COO.<\/strong><\/p>\n\n\n\n<p id=\"5a65\">Cada \u00e1rea tiene una tem\u00e1tica sobre la cual es responsable, y trabajamos de manera coordinada, en red. Esto significa que todos somos responsables del crecimiento, de las operaciones, de innovar, de la cultura, del cuidado de las personas, de contar lo que hacemos y de la sostenibilidad.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p id=\"2089\">\u201cEl \u00e1rea de operaciones es el motor que mueve una empresa, especialmente una con una fuerte componente basada en servicios como la nuestra. En gran medida, es la que hace a Abstracta posible\u201d, esboz\u00f3 Federico. \u201cEl rol de Chief Operations Officer es exigente, y lo hice siempre consciente de c\u00f3mo y por qu\u00e9 hacerlo.&nbsp;<strong>Estoy muy agradecido de haber podido llevarlo adelante en red.&nbsp;<\/strong>En los \u00faltimos a\u00f1os, viviendo en San Francisco, estuve explorando otros roles, para lo cual Ale fue una excelente aliada\u201d, agreg\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p id=\"f066\">\u201cGeneramos un muy buen equipo, y pudo ir tomando de a poco nuevas responsabilidades que me permitieron ir cambiando mi rol a m\u00ed tambi\u00e9n. Trabaj\u00f3 en conjunto con los l\u00edderes, growth y las \u00e1reas de soporte, y generaron una red de trabajo en la que creemos y queremos seguir apoyando.&nbsp;<strong>Con su trabajo y esfuerzo, ha venido coconstruyendo el nuevo rol de COO, y nos ha llevado a otro nivel de madurez como empresa, con lo cual hoy este cambio de rol nos resulta natura<\/strong>l\u201d, sostuvo.<\/p>\n\n\n\n<p id=\"7974\">\u201cSi bien era algo que naturalmente se vislumbraba como parte de mi plan de carrera, el nombramiento me sorprendi\u00f3. \u00a1Muy gratamente por cierto! A medida que uno transita su carrera laboral y va creciendo en <em>seniority<\/em>, es normal que los diferentes roles duren m\u00e1s tiempo porque la curva de crecimiento se hace menos empinada: a mayor responsabilidad, m\u00e1s tiempo se espera que se est\u00e9 en el rol, ya sea por aprendizaje o porque las tareas y objetivos suelen conllevar procesos m\u00e1s largos\u201d, expres\u00f3 Alejandra.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p id=\"74a1\"><strong>\u201cSoy mujer, tengo m\u00e1s de 40 a\u00f1os, y trabajo en el \u00e1rea de tecnolog\u00eda. Esta oportunidad se me presenta como una gran oportunidad en mi vida, y tambi\u00e9n es una forma de evidenciar c\u00f3mo hacemos las cosas en Abstracta. Poder ser testigo y mostrar este impacto en primera persona, hacia adentro y afuera de la compa\u00f1\u00eda, me hace sumamente feliz y me empodera para seguir creciendo y aportando\u201d, destac\u00f3.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p id=\"facf\"><strong>Como Chief Quality Officer, Federico seguir\u00e1 colaborando con el equipo de Operaciones<\/strong>&nbsp;para brindar apoyo en la ejecuci\u00f3n de proyectos con las mejores pr\u00e1cticas de calidad; con el equipo de&nbsp;<strong>Growth<\/strong>, para ofrecer soporte en la elaboraci\u00f3n de propuestas que se ajusten a las necesidades de calidad de los nuevos clientes; y con el equipo de&nbsp;<strong>Marketing<\/strong>, para continuar compartiendo aprendizajes en distintos medios, con el fin de potenciar a las comunidades en las cuales trabajamos y seguir impulsando el crecimiento de nuestra disciplina. Este \u00faltimo punto lleva a capitalizar y compartir conocimiento, y generar puentes con otras personas y empresas, para colaborar en la cocreaci\u00f3n de software de primer nivel.<\/p>\n\n\n\n<p id=\"07fa\"><strong>\u00bfA qu\u00e9 se dedica el \u00e1rea de Operaciones de Abstracta? Conoce ac\u00e1 sus mayores objetivos y desaf\u00edos, en la voz de Alejandra Viglietti.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"c0ef\"><strong>Objetivos<\/strong><\/h2>\n\n\n\n<p id=\"d3be\"><strong>Operaciones se ocupa de todo lo referente al servicio brindado por Abstracta a sus clientes desde el punto de vista de ejecuci\u00f3n del mismo. Se trata de un trabajo clave para el funcionamiento y crecimiento de la empresa.<\/strong><\/p>\n\n\n\n<p id=\"a29a\">Cuando hay nuevas oportunidades, ya sea con un nuevo cliente o un cliente existente que necesita una nueva asignaci\u00f3n, realizamos una labor muy importante para lograr el&nbsp;<strong><em>matcheo<\/em> entre el requerimiento del proyecto y las personas que lo llevar\u00e1n adelante.<\/strong><\/p>\n\n\n\n<p id=\"6b70\">Consideramos m\u00faltiples variables para llevar a cabo cada asignaci\u00f3n, desde los requisitos y el contexto de los proyectos, hasta las oportunidades de crecimiento de las personas, sus skills, sus necesidades personales, experiencias pasadas en cuanto a las personas con las que ha trabajado o con las que comenzar\u00eda a trabajar, ambiciones y gustos, entre otras.<\/p>\n\n\n\n<p id=\"db01\"><strong>Algunas de las cosas que esto implica son:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comprender cabalmente las&nbsp;<strong>necesidades actuales y futuras del proyecto<\/strong>&nbsp;y el equipo del cliente.<\/li>\n\n\n\n<li>Conocer las&nbsp;<strong>capacidades de nuestro equipo&nbsp;<\/strong>actual, los intereses y potencialidades de las personas que son elegibles para el proyecto en cuesti\u00f3n.<\/li>\n\n\n\n<li>Dise\u00f1ar el perfil de contrataci\u00f3n en caso de no contar con las personas id\u00f3neas en ese momento.<\/li>\n\n\n\n<li>Considerar la&nbsp;<strong>combinaci\u00f3n de perfiles<\/strong>&nbsp;para formar equipos diversos y de alto desempe\u00f1o.<\/li>\n\n\n\n<li><strong>Asegurar para el equipo, los recursos necesarios&nbsp;<\/strong>para la ejecuci\u00f3n del proyecto.<\/li>\n\n\n\n<li>Brindar las<strong>&nbsp;capacitaciones&nbsp;<\/strong>necesarias para poder asumir el desaf\u00edo de la mejor manera posible.<\/li>\n\n\n\n<li><strong>Interiorizarse sobre la evoluci\u00f3n y procesos<\/strong>&nbsp;de las eventuales contrataciones.<\/li>\n<\/ul>\n\n\n\n<p id=\"4ff2\"><strong>En definitiva, desde Operaciones se eval\u00faan diferentes escenarios y se toman las mejores decisiones posibles, con apoyo en la red de Growth, Sustainability y People Care.<\/strong><\/p>\n\n\n\n<p id=\"54de\"><strong>Para esto, se toman en cuenta:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las necesidades actuales de cada cliente y su potencial estrat\u00e9gico para Abstracta.<\/li>\n\n\n\n<li>Las necesidades de las personas del equipo, sus ambiciones y proyectos de desarrollo personales.<\/li>\n\n\n\n<li>Las oportunidades de crecimiento de Abstracta como empresa formadora y thought leaders.<\/li>\n<\/ul>\n\n\n\n<p id=\"883e\">Luego de realizar las asignaciones e iniciado el proyecto, el \u00e1rea realiza un&nbsp;<strong>acompa\u00f1amiento y asesoramiento permanente<\/strong>&nbsp;con el objetivo de aportar valor en todas las etapas y garantizar experiencias \u00f3ptimas para todas las personas involucradas.<\/p>\n\n\n\n<p id=\"ced1\"><strong>Nuestra labor no termina con la realizaci\u00f3n de las asignaciones, en realidad se trata solo del comienzo. Realizamos el seguimiento de cada proyecto para lograr aportar el m\u00e1ximo valor posible en todas sus etapas y realizar ajustes cuando resulta necesario.<\/strong><\/p>\n\n\n\n<p id=\"ba45\">Hacemos especial<strong>&nbsp;foco en las personas<\/strong>&nbsp;que trabajan en los diferentes proyectos con el fin de potenciar sus habilidades, promover su crecimiento profesional y posibilidades de aprendizaje, cuidar el balance vida-trabajo, explotar todas las oportunidades de crecimiento y, en definitiva, garantizar la mejor experiencia posible para ellas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2977\"><strong>Desaf\u00edos<\/strong><\/h2>\n\n\n\n<p id=\"d063\"><strong>Uno de nuestros mayores desaf\u00edos es poder distribuir las responsabilidades de manera clara<\/strong>, para que todas las personas sepan en qui\u00e9n apoyarse en cada momento y ante cada necesidad, tanto en lo t\u00e9cnico como en otros aspectos. Del mismo modo, evitar la sobre exigencia, comprender lo que cada persona de nuestro equipo necesita, cu\u00e1les son sus motivaciones y objetivos de crecimiento.<\/p>\n\n\n\n<p id=\"d8a5\"><strong>Hacer un match entre esto y lo que el cliente quiere resulta fundamental<\/strong>&nbsp;en nuestro trabajo, pero m\u00e1s a\u00fan aportar a lo que verdaderamente necesita, m\u00e1s all\u00e1 de lo que pide, para acompa\u00f1arlo en su \u00e9xito.<\/p>\n\n\n\n<p id=\"d352\">Trabajamos con atenci\u00f3n a todos los detalles para lograr que las personas se sientan a gusto con las tareas asignadas y sus l\u00edderes, y que nuestros clientes sientan que tienen el mejor equipo para trabajar.<\/p>\n\n\n\n<p id=\"7e8f\">Otro gran desaf\u00edo es<strong>&nbsp;anticiparnos a las futuras necesidades y contar con las personas id\u00f3neas<\/strong>&nbsp;para las oportunidades que puedan concretarse. Con esto, buscamos minimizar los tiempos de espera del cliente y a su vez que las personas se mantengan motivadas, en un <a href=\"https:\/\/es.abstracta.us\/blog\/importancia-liderazgo-humanista-equidad-salarial-mercado-laboral-ti\/\" target=\"_blank\" rel=\"noreferrer noopener\">mercado cuya demanda es mayor que la oferta<\/a> y que tiene una rotaci\u00f3n muy alta.<\/p>\n\n\n\n<p id=\"b522\">A futuro, nos proponemos tomar la responsabilidad de colaborar con el \u00e1rea de Innovaci\u00f3n de Abstracta, en los casos en que los clientes requieren crear nuevas soluciones. Para ello, tenemos que considerar a nuestra red de partners, y evaluar si es necesario crear nuevas tecnolog\u00edas. Lograr innovaciones en testing de software es crucial en el camino de Abstracta. En <a href=\"https:\/\/es.abstracta.us\/blog\/innovaciones-testing-software\/\" target=\"_blank\" rel=\"noreferrer noopener\">este&nbsp;art\u00edculo<\/a>, puedes encontrar m\u00e1s informaci\u00f3n sobre las innovaciones en testing realizadas por nuestra empresa.<\/p>\n\n\n\n\n\n<p><strong>\u00a1S\u00edguenos en\u00a0<a href=\"https:\/\/bit.ly\/LinkedIn-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>,\u00a0<a href=\"https:\/\/bit.ly\/TW-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a>,\u00a0<a href=\"https:\/\/bit.ly\/FB-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>,\u00a0<a href=\"https:\/\/bit.ly\/Instagram-Abstracta-Latam\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0y\u00a0<a href=\"https:\/\/bit.ly\/YT-Abstracta\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>\u00a0para conocer m\u00e1s sobre nuestra cultura y ser parte de nuestra comunidad!<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/medium.com\/@abstracta?source=post_page-----6618a9deacd3--------------------------------\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.<\/p>\n","protected":false},"author":21,"featured_media":17807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[62,145],"class_list":["post-17795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liderazgo","tag-calidad-software","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer - Abstracta<\/title>\n<meta name=\"description\" content=\"Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer - Abstracta\" \/>\n<meta property=\"og:description\" content=\"Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AbstractaChile\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T14:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-15T18:56:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/02\/nuevos-chief-operations-quality-officer-abstracta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matias Reina, CoCEO en Abstracta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:site\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matias Reina, CoCEO en Abstracta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\"},\"author\":{\"name\":\"Matias Reina, CoCEO en Abstracta\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/fe2e4bab70397fb0b4a07f2d8ceca3f0\"},\"headline\":\"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer\",\"datePublished\":\"2023-02-03T14:16:00+00:00\",\"dateModified\":\"2024-05-15T18:56:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\"},\"wordCount\":1423,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"keywords\":[\"Calidad de Software\",\"Tecnolog\u00eda\"],\"articleSection\":[\"Liderazgo\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\",\"url\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\",\"name\":\"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer - Abstracta\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\"},\"datePublished\":\"2023-02-03T14:16:00+00:00\",\"dateModified\":\"2024-05-15T18:56:00+00:00\",\"description\":\"Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/es.abstracta.us\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"name\":\"Abstracta\",\"description\":\"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.\",\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\",\"name\":\"Abstracta\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"contentUrl\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"width\":1217,\"height\":300,\"caption\":\"Abstracta\"},\"image\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/we_are_abstracta\/\",\"https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/\",\"https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ\",\"https:\/\/www.facebook.com\/AbstractaChile\/\",\"https:\/\/twitter.com\/AbstractaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/fe2e4bab70397fb0b4a07f2d8ceca3f0\",\"name\":\"Matias Reina, CoCEO en Abstracta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e631f3dfc7128f794190c1163b341d0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e631f3dfc7128f794190c1163b341d0a?s=96&d=mm&r=g\",\"caption\":\"Matias Reina, CoCEO en Abstracta\"},\"description\":\"CEO en Abstracta Inc.\",\"sameAs\":[\"http:\/\/cl.abstracta.us\",\"https:\/\/www.linkedin.com\/in\/matiasreina\/\"],\"url\":\"https:\/\/es.abstracta.us\/blog\/author\/matias-reina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer - Abstracta","description":"Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer - Abstracta","og_description":"Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.","og_url":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/","og_site_name":"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta","article_publisher":"https:\/\/www.facebook.com\/AbstractaChile\/","article_published_time":"2023-02-03T14:16:00+00:00","article_modified_time":"2024-05-15T18:56:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/02\/nuevos-chief-operations-quality-officer-abstracta.png","type":"image\/png"}],"author":"Matias Reina, CoCEO en Abstracta","twitter_card":"summary_large_image","twitter_creator":"@AbstractaChile","twitter_site":"@AbstractaChile","twitter_misc":{"Written by":"Matias Reina, CoCEO en Abstracta","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#article","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/"},"author":{"name":"Matias Reina, CoCEO en Abstracta","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/fe2e4bab70397fb0b4a07f2d8ceca3f0"},"headline":"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer","datePublished":"2023-02-03T14:16:00+00:00","dateModified":"2024-05-15T18:56:00+00:00","mainEntityOfPage":{"@id":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/"},"wordCount":1423,"commentCount":0,"publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"keywords":["Calidad de Software","Tecnolog\u00eda"],"articleSection":["Liderazgo"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/","url":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/","name":"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer - Abstracta","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/#website"},"datePublished":"2023-02-03T14:16:00+00:00","dateModified":"2024-05-15T18:56:00+00:00","description":"Alejandra Viglietti, Operations Manager por casi 2 a\u00f1os, es la nueva Chief Operations Officer (COO) de Abstracta, en reemplazo de\u00a0Federico Toledo, cofundador y socio de la empresa. Federico ocup\u00f3 el puesto por m\u00e1s de 5 a\u00f1os, y asumi\u00f3 ahora como Chief Quality Officer (CQO). De este modo, Alejandra se uni\u00f3 al C-Suite de la compa\u00f1\u00eda.","breadcrumb":{"@id":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/es.abstracta.us\/blog\/nuevos-chief-operations-quality-officer-abstracta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.abstracta.us\/blog\/"},{"@type":"ListItem","position":2,"name":"Nueva COO en Abstracta y creaci\u00f3n del puesto Chief Quality Officer"}]},{"@type":"WebSite","@id":"https:\/\/es.abstracta.us\/blog\/#website","url":"https:\/\/es.abstracta.us\/blog\/","name":"Abstracta","description":"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.","publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/es.abstracta.us\/blog\/#organization","name":"Abstracta","url":"https:\/\/es.abstracta.us\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","contentUrl":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","width":1217,"height":300,"caption":"Abstracta"},"image":{"@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/we_are_abstracta\/","https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/","https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ","https:\/\/www.facebook.com\/AbstractaChile\/","https:\/\/twitter.com\/AbstractaChile"]},{"@type":"Person","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/fe2e4bab70397fb0b4a07f2d8ceca3f0","name":"Matias Reina, CoCEO en Abstracta","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e631f3dfc7128f794190c1163b341d0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e631f3dfc7128f794190c1163b341d0a?s=96&d=mm&r=g","caption":"Matias Reina, CoCEO en Abstracta"},"description":"CEO en Abstracta Inc.","sameAs":["http:\/\/cl.abstracta.us","https:\/\/www.linkedin.com\/in\/matiasreina\/"],"url":"https:\/\/es.abstracta.us\/blog\/author\/matias-reina\/"}]}},"jetpack_featured_media_url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/02\/nuevos-chief-operations-quality-officer-abstracta.png","_links":{"self":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/17795"}],"collection":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/comments?post=17795"}],"version-history":[{"count":5,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/17795\/revisions"}],"predecessor-version":[{"id":17808,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/17795\/revisions\/17808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media\/17807"}],"wp:attachment":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media?parent=17795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/categories?post=17795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/tags?post=17795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}