{"id":17343,"date":"2024-04-05T10:22:39","date_gmt":"2024-04-05T13:22:39","guid":{"rendered":"https:\/\/es.abstracta.us\/blog\/?p=17343"},"modified":"2024-09-26T17:30:50","modified_gmt":"2024-09-26T20:30:50","slug":"quality-sense-conf-colombia","status":"publish","type":"post","link":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/","title":{"rendered":"Se viene Quality Sense Conf 2024, en Colombia"},"content":{"rendered":"\n<p>Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un <em>hub <\/em>digital en el mundo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024.png\" alt=\"Quality Sense Conf Colombia 2024\" class=\"wp-image-17330\" srcset=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024.png 960w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024-300x169.png 300w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024-768x432.png 768w, https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024-18x10.png 18w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p><br><strong>La <a href=\"https:\/\/qualitysenseconf.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quality Sense Conf<\/a> cobra cada vez mayor relevancia en el escenario tecnol\u00f3gico global y queremos contarte todo lo que se viene con tiempo,<\/strong> <strong>para que puedas sumarte y participar de la manera que mejor te resulte, como <em>speaker<\/em>, <em>sponsor<\/em> y asistente.<\/strong><\/p>\n\n\n\n<p><strong>La cita es el 21 y 22 de octubre en las oficinas de <\/strong><a href=\"https:\/\/www.endava.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>Endava<\/strong><\/a><strong> (nuestro <em>venue sponsor<\/em> ya confirmado) en Medell\u00edn.<\/strong> Durante el primer d\u00eda, el evento ser\u00e1 online, y el 2do d\u00eda ser\u00e1 completamente presencial.<\/p>\n\n\n\n<p>Grabaremos todas las charlas para disponibilizarlas luego en nuestro <a href=\"https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ\" target=\"_blank\" rel=\"noreferrer noopener\">canal de Youtube<\/a>, tal como realizamos en las ediciones previas, con el fin de ampliar a\u00fan m\u00e1s el acceso al conocimiento, mediante videos accesibles con subt\u00edtulos y en distintos idiomas.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#f1f1f1\"><strong>\ud83d\udc49 Asegura tu lugar ahora y s\u00e9 parte de esta experiencia \u00fanica desde cualquier parte del mundo. \u00a1<a href=\"https:\/\/www.eventbrite.com\/e\/quality-sense-conference-2024-tickets-1003535550847\" target=\"_blank\" rel=\"noreferrer noopener\">Reg\u00edstrate sin costo aqu\u00ed<\/a>!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#QSConf 2023 Chile (Recap)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/udRadae14TY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><em>Te invitamos a revivir la Quality Sense Conf 2023 de Chile en este video.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Medell\u00edn: un destino Inspirador<\/strong><\/h2>\n\n\n\n<p>Conocida como la ciudad de la eterna primavera y reconocida como el \u201cDistrito Especial de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n de Colombia\u201d, <strong>Medell\u00edn ofrece un escenario vibrante y propicio para la Quality Sense Conf 2024<\/strong>.<\/p>\n\n\n\n<p>Su rica cultura, belleza natural y hospitalidad, combinados con su creciente enfoque en la tecnolog\u00eda y la innovaci\u00f3n, hacen de esta ciudad colombiana el lugar perfecto para reunirse, aprender y compartir conocimientos.<\/p>\n\n\n\n<p>Como parte de las actividades que planificamos por el evento, nos enorgullece ofrecer a nuestros <em>speakers<\/em> y <em>sponsors<\/em> la oportunidad de explorar la belleza de Antioquia con un paseo a una finca cafetera.<\/p>\n\n\n\n<p>Desde las majestuosas monta\u00f1as hasta los encantadores pueblos, este paseo no solo es una experiencia cultural \u00fanica, sino tambi\u00e9n una oportunidad<strong> para conocernos, conectarnos y fortalecer nuestros lazos en un entorno inspirador<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#FAQS<em> <\/em>Algunas preguntas y respuestas<\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&#8211; \u00bfPor qu\u00e9 llevamos adelante la Quality Sense Conf en Colombia?<\/strong><\/h2>\n\n\n\n<p>En marzo de 2024,<a href=\"https:\/\/es.abstracta.us\/blog\/nueva-oficina-abstracta-colombia\/\" target=\"_blank\" rel=\"noreferrer noopener\"> anunciamos la apertura de una nueva oficina de Abstracta en Colombia<\/a>, de la mano de la <em>thought leader <\/em><a href=\"https:\/\/www.linkedin.com\/in\/mercedesquinterom\" target=\"_blank\" rel=\"noreferrer noopener\">Mercedes Quintero Mart\u00ednez<\/a>, con quien compartimos no solo los objetivos y visi\u00f3n, sino tambi\u00e9n los prop\u00f3sitos y una cultura profundamente humanista y de cuidado mutuo.<\/p>\n\n\n\n<p><strong>Mercedes Quintero es la fundadora de Qualitas Test Team, una empresa colombiana que cuenta con 10 a\u00f1os de trayectoria impactando en la calidad de vida de muchas personas y llevando oportunidades a donde m\u00e1s se necesita<\/strong>, mediante trabajos de calidad, propuestas de valor y servicios de excelencia.<\/p>\n\n\n\n<p><strong>La alianza que celebramos en 2023 con Qualitas Test Team llev\u00f3 a nuestra fusi\u00f3n <\/strong>y al nacimiento de una nueva oficina de Abstracta en Colombia, con el objetivo de nutrirnos mutuamente, expandir nuestros servicios, y potenciar el desarrollo de software a nivel regional y global.<\/p>\n\n\n\n<p>Por eso, luego de haber celebrado la 1era edici\u00f3n de la <a href=\"https:\/\/federico-toledo.com\/quality-sense-conf-2022-recuerdos-del-evento\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quality Sense Conf en Uruguay en 2022<\/a> y la <a href=\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-evento-tecnologia-calidad-software-latam\/\" target=\"_blank\" rel=\"noreferrer noopener\">segunda en Chile en 2023<\/a>,<strong> nos llena de entusiasmo organizarla en Colombia en 2024, con todo el apoyo de esta gran l\u00edder emprendedora y su equipo.<\/strong><\/p>\n\n\n\n<p>Tenemos plena convicci\u00f3n de que Colombia y toda Am\u00e9rica Latina tienen much\u00edsimo potencial para aportar a una industria pujante como las TIC y, a su vez, mucho para crecer. Tanto en infraestructura y servicios digitales como en diversidad y cultura.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&#8211; \u00bfCu\u00e1l es el costo de la entrada al evento?<\/strong><\/h2>\n\n\n\n<p>Como en los a\u00f1os anteriores, la entrada es libre y gratuita.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&#8211; \u00bfQu\u00e9 gana Abstracta invirtiendo tanto en un evento gratuito?<\/strong><\/h2>\n\n\n\n<p>Se trata de un evento autogestionado con los aportes de <em>sponsors<\/em> y participaci\u00f3n de diversidad de <em>speakers,<\/em> de diferentes partes del mundo.<\/p>\n\n\n\n<p>Gracias a nuestros m\u00e1s de 15 a\u00f1os de experiencia en la industria, sabemos que forjar redes es una de las actividades m\u00e1s relevantes para lograr nuevas oportunidades de desarrollo. <strong>Si crece el ecosistema, crece cada integrante de nuestra comunidad. <\/strong><\/p>\n\n\n\n<p>Por eso, nos enorgullece poder aportar a la construcci\u00f3n de puentes y v\u00ednculos, y ser parte de algo mucho m\u00e1s grande a\u00fan que nuestra propia empresa: el impacto de la industria en la sociedad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&#8211; \u00bfQu\u00e9 temas trataremos en la QSConf 2024?<\/strong><\/h2>\n\n\n\n<p>Disfrutaremos charlas de diversidad de <em>speakers<\/em> de diferentes partes del mundo. Abordaremos una amplia gama de tem\u00e1ticas:<\/p>\n\n\n\n<p>\u2705 <a href=\"https:\/\/es.abstracta.us\/blog\/guia-crear-estrategia-pruebas-software-adecuada\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estrategias de calidad<\/a> de empresas latinoamericanas de gran escala<\/p>\n\n\n\n<p>\u2705 Calidad de datos<\/p>\n\n\n\n<p>\u2705 Ciberseguridad<\/p>\n\n\n\n<p>\u2705 Aplicaciones potenciadas con <a href=\"https:\/\/es.abstracta.us\/blog\/inteligencia-artificial-generativa-potenciar-empresa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inteligencia Artificial Generativa<\/a><\/p>\n\n\n\n<p>\u2705 Desarrollo de herramientas <em>open-source<\/em><\/p>\n\n\n\n<p><em>\u2705 <\/em>Testing funcional y no funcional en distintos contextos<\/p>\n\n\n\n<p>\u2705 <a href=\"https:\/\/es.abstracta.us\/soluciones\/automatizacion-pruebas\" target=\"_blank\" rel=\"noreferrer noopener\">Automatizaci\u00f3n<\/a>, <a href=\"https:\/\/es.abstracta.us\/blog\/observabilidad-testing-software\/\" target=\"_blank\" rel=\"noreferrer noopener\">observabilidad<\/a> y mecanismos para mantener nuestras aplicaciones con altos est\u00e1ndares de calidad<\/p>\n\n\n\n<p>\u2705 <a href=\"https:\/\/es.abstracta.us\/soluciones\/pruebas-de-performance\" target=\"_blank\" rel=\"noreferrer noopener\">Performance<\/a><\/p>\n\n\n\n<p>\u2705 <a href=\"https:\/\/es.abstracta.us\/soluciones\/pruebas-de-accesibilidad\" target=\"_blank\" rel=\"noreferrer noopener\">Accesibilidad<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><em>&#8211; <\/em>\u00bfQu\u00e9 buscamos con este evento?<\/strong><\/h2>\n\n\n\n<p>Seguir ampliando el acceso al conocimiento, con el fin de que la comunidad IT se desarrolle de manera profesional cada d\u00eda m\u00e1s, y continuar posicionando a Am\u00e9rica Latina como <em>hub <\/em>digital en el mundo, en relaci\u00f3n al desarrollo de software de calidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&#8211; \u00bfQu\u00e9 puedes ganar al sumarte a este evento?<\/strong><\/h2>\n\n\n\n<p>Independientemente de la modalidad que elijas para participar en la Quality Sense Conf, cada una ofrece beneficios \u00fanicos y genera un impacto positivo tanto en tu desarrollo profesional como en la industria en su conjunto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como asistente:<\/strong><\/h3>\n\n\n\n<p>Participar en la conferencia te permite estar al d\u00eda con las \u00faltimas tendencias y herramientas del sector. Te brinda la oportunidad de forjar redes con personas en puestos directivos y tomadoras de decisiones, aprovechar las oportunidades de aprendizaje que surgen a partir de la interacci\u00f3n con otros profesionales, enriquecer tu perspectiva y ampliar tu red de contactos. Conoce los <a href=\"https:\/\/es.abstracta.us\/blog\/valores-pilares-quality-sense-conf\/\" target=\"_blank\" rel=\"noreferrer noopener\">valores y c\u00f3digo de conducta<\/a> de la conferencia. Para reservar tu cupo, te invitamos a <a href=\"https:\/\/www.eventbrite.com\/e\/quality-sense-conference-2024-tickets-1003535550847\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>registrarte sin costo aqu\u00ed<\/strong><\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como <em>speaker<\/em>:<\/strong><\/h3>\n\n\n\n<p>Al compartir tu conocimiento y experiencia, apoyas la difusi\u00f3n de pr\u00e1cticas innovadoras y sostenibles. Te posicionas como referente en la industria, lo cual ampl\u00eda tu influencia y contribuye al crecimiento profesional de la comunidad y al desarrollo de la industria. Tambi\u00e9n te ayuda a seguir forjando redes y cultivar nuevas oportunidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como <em>sponsor<\/em>:<\/strong><\/h3>\n\n\n\n<p>Tu marca gana visibilidad tanto entre asistentes y <em>speakers<\/em> como en la comunidad. Te destacas como empresa empleadora o proveedora de servicios de primer nivel y muestras tu apoyo a eventos que fomentan la sostenibilidad y la innovaci\u00f3n en la industria. Amplias tus redes y e impulsas nuevas oportunidades de negocio y colaboraci\u00f3n<strong>. Para m\u00e1s informaci\u00f3n sobre oportunidades de patrocinio, <a href=\"https:\/\/qualitysenseconf.com\/sponsorship\/\" target=\"_blank\" rel=\"noreferrer noopener\">cont\u00e1ctanos aqu\u00ed<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Testimonios de sponsors<\/strong><\/h2>\n\n\n\n<p>Con el fin de dimensionar el impacto y repercusiones del evento, compartimos los testimonios de algunos de los <em>sponsors<\/em> de la Quality Sense Conf 2023:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cHab\u00edamos participado de la edici\u00f3n del a\u00f1o pasado en Montevideo sin ser<em> sponsors<\/em>, y ver el nivel del evento nos impuls\u00f3 a sponsorear este a\u00f1o. Nuestras expectativas fueron superadas: cumplimos con los objetivos comerciales, hicimos mucho networking, nos nutrimos con las charlas, y la pasamos muy bien entre amigos. Trajimos nuevos contactos, generamos contenido y el sorteo de becas de Academy de Crowdar nos dio la posibilidad de desarrollar mayor presencia en el mercado de Chile\u201d (<a href=\"https:\/\/www.crowdaronline.com\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>Crowdar<\/strong><\/a>).<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cConsideramos que la Quality Sense Conf es una de las mejores conferencias de testing en Am\u00e9rica Latina. Tanto por la calidad de sus charlas y speakers, organizaci\u00f3n, y reputaci\u00f3n de las personas que la organizan como de las que participan\u201d (<a href=\"https:\/\/www.endava.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>Endava<\/strong><\/a>).<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cDecidimos ser sponsors de QSConf 2023 para apoyar la iniciativa y para incrementar el reconocimiento de Grafana en Latam. El ambiente y energ\u00eda del evento fue genial. Siempre que Grafana apruebe el presupuesto, nos gustar\u00eda mucho volver a ser sponsors en 2024, esta vez en Colombia\u201d (<a href=\"https:\/\/k6.io\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>Grafana K6<\/strong><\/a>).<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cNos gusta ser parte de este evento porque nos permite forjar redes y relaciones importantes con personas y compa\u00f1\u00edas de alto nivel en el \u00e1rea de IT. Ser sponsors del QSConf 2023 impact\u00f3 de una manera positiva: nos ayud\u00f3 a forjar redes y branding. Nos permiti\u00f3 darnos cuenta de c\u00f3mo nos perciben y de c\u00f3mo podemos ayudar a crecer la comunidad de testing en Latinoam\u00e9rica\u201d (<a href=\"https:\/\/qaminds.com\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>QAminds<\/strong><\/a>).<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cDecidimos ser<em> sponsors<\/em> de QSConf2023 por ser un evento enfocado en Ingenier\u00eda de Calidad exclusivamente y en el \u00e1mbito latinoamericano. Aunque existen eventos con este enfoque, suelen ser lejanos en sus localizaciones, lo cual dificulta el acceso. Nuestra participaci\u00f3n no fue presencial, sino \u00fanicamente virtual. Este aspecto nos parece muy relevante ya que as\u00ed se rompen las barreras f\u00edsicas para la participaci\u00f3n\u201d (<a href=\"https:\/\/softesting.com\/es_es\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>Softesting<\/strong><\/a>).<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cFue una gran experiencia, al ser la primera Quality Sense Conf en la cual participamos super\u00f3 nuestras expectativas. Conseguimos conectarnos con empresas que ya han interactuado con Datadog pero que hacen parte de otros departamentos y pueden encontrar ah\u00ed diferentes soluciones dependiendo de su \u00e1rea\u201d (<a href=\"https:\/\/www.datadoghq.com\/\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\"><strong>Datadog<\/strong><\/a>).<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Tal como expres\u00f3 el cofundador de Abstracta y organizador principal del evento Federico Toledo en su <\/strong><a href=\"https:\/\/youtu.be\/zGtJMI7xu74?si=Xdv7az4gkLuVcoIm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>charla final<\/strong><\/a><strong> de Quality Sense Conf 2023, \u201cgran parte de lo que le da valor a la conferencia son las charlas y los espacios de networking, pero nada de eso podr\u00edamos lograrlo sin el apoyo de los <em>sponsors<\/em> que conf\u00edan en nuestra propuesta\u201d.<\/strong><\/p>\n\n\n\n<p>\u00bfTe gustar\u00eda conocer los testimonios completos de los <em>sponsors&nbsp;y speakers<\/em> de la edici\u00f3n 2023 en Chile? <a href=\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-evento-tecnologia-calidad-software-latam\/\" target=\"_blank\" rel=\"noreferrer noopener\">No te pierdas este art\u00edculo.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mirando hacia adelante<\/h2>\n\n\n\n<p><strong>Luego de nuestra 3era edici\u00f3n, en Colombia, proyectamos aterrizar en M\u00e9xico<\/strong> (quiz\u00e1 en 2025), donde hay una comunidad muy fuerte y tenemos muy buenos v\u00ednculos, que nos podr\u00edan ayudar a generar una instancia de calidad.<\/p>\n\n\n\n<p><strong>A futuro, tenemos la idea de llevar el evento a Estados Unidos y en espa\u00f1ol<\/strong>, con mayoritariamente <em>speakers<\/em> de Latam, para acercar all\u00ed los valores y objetivos de nuestra conferencia.<\/p>\n\n\n\n<p>Lo cierto es que nuestra presencia en eventos no es algo nuevo: desde nuestros inicios, all\u00e1 por 2008, siempre hicimos mucho foco en participar y organizar diferentes tipos de eventos de nuestra industria, as\u00ed como gestionar distintos tipos de espacios para compartir conocimientos y empoderar a nuestra comunidad.<\/p>\n\n\n\n<p><strong>Todos estos tipos de instancias nos ayudan a construir puentes globales y a que la comunidad IT gane valor, aprendizajes y conexiones que favorezcan el desarrollo de la industria, y maximicen su impacto en nuestra sociedad.<\/strong><\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#f1f1f1\"><strong>\ud83d\udc49 \u00danete a esta conferencia pionera sobre calidad de software de Latinoam\u00e9rica y conecta con grandes referentes de la industria. \u00a1<a href=\"https:\/\/www.eventbrite.com\/e\/quality-sense-conference-2024-tickets-1003535550847\" target=\"_blank\" rel=\"noreferrer noopener\">Reg\u00edstrate sin costo aqu\u00ed<\/a>!<\/strong><\/p>\n\n\n\n<p><strong>\u00a1S\u00edguenos en <a href=\"https:\/\/bit.ly\/LinkedIn-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>, <a href=\"https:\/\/bit.ly\/TW-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">X<\/a>, <a href=\"https:\/\/bit.ly\/FB-Abstracta-Chile\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, <a href=\"https:\/\/bit.ly\/Instagram-Abstracta-Latam\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> y <a href=\"https:\/\/bit.ly\/YT-Abstracta\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a> para enterarte de todas las novedades y avances de la Quality Sense Conf 2024!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.<\/p>\n","protected":false},"author":35,"featured_media":17330,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229],"tags":[3,62,146,227,134,231,120,2,223,17],"class_list":["post-17343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-automatizacion-pruebas","tag-calidad-software","tag-eventos","tag-pruebas-basadas-en-datos","tag-pruebas-accesibilidad","tag-pruebas-de-observabilidad","tag-pruebas-performance","tag-pruebas-funcionales","tag-quality-sense-conf","tag-testing-software"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se viene Quality Sense Conf 2024, en Colombia - Abstracta<\/title>\n<meta name=\"description\" content=\"Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se viene Quality Sense Conf 2024, en Colombia - Abstracta\" \/>\n<meta property=\"og:description\" content=\"Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AbstractaChile\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T13:22:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T20:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Natalie Rodgers, Marketing Team Lead\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:site\" content=\"@AbstractaChile\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalie Rodgers, Marketing Team Lead\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\"},\"author\":{\"name\":\"Natalie Rodgers, Marketing Team Lead\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/b7978e8cd73ff3ed2dcc7e127499b4cb\"},\"headline\":\"Se viene Quality Sense Conf 2024, en Colombia\",\"datePublished\":\"2024-04-05T13:22:39+00:00\",\"dateModified\":\"2024-09-26T20:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\"},\"wordCount\":1792,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"keywords\":[\"Automatizaci\u00f3n de Pruebas\",\"Calidad de Software\",\"Eventos\",\"Pruebas Basadas en Datos\",\"Pruebas de Accesibilidad\",\"Pruebas de Observabilidad\",\"Pruebas de Performance\",\"Pruebas Funcionales\",\"Quality Sense Conf\",\"Testing de Software\"],\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\",\"url\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\",\"name\":\"Se viene Quality Sense Conf 2024, en Colombia - Abstracta\",\"isPartOf\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\"},\"datePublished\":\"2024-04-05T13:22:39+00:00\",\"dateModified\":\"2024-09-26T20:30:50+00:00\",\"description\":\"Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.\",\"breadcrumb\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/es.abstracta.us\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se viene Quality Sense Conf 2024, en Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#website\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"name\":\"Abstracta\",\"description\":\"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.\",\"publisher\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#organization\",\"name\":\"Abstracta\",\"url\":\"https:\/\/es.abstracta.us\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"contentUrl\":\"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png\",\"width\":1217,\"height\":300,\"caption\":\"Abstracta\"},\"image\":{\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/we_are_abstracta\/\",\"https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/\",\"https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ\",\"https:\/\/www.facebook.com\/AbstractaChile\/\",\"https:\/\/twitter.com\/AbstractaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/b7978e8cd73ff3ed2dcc7e127499b4cb\",\"name\":\"Natalie Rodgers, Marketing Team Lead\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a23da822367e20ddb98b59d5273eb3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a23da822367e20ddb98b59d5273eb3e?s=96&d=mm&r=g\",\"caption\":\"Natalie Rodgers, Marketing Team Lead\"},\"sameAs\":[\"https:\/\/es.abstracta.us\/\"],\"url\":\"https:\/\/es.abstracta.us\/blog\/author\/natalie-rodgers\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se viene Quality Sense Conf 2024, en Colombia - Abstracta","description":"Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"Se viene Quality Sense Conf 2024, en Colombia - Abstracta","og_description":"Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.","og_url":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/","og_site_name":"Blog de Desarrollo de Software, Testing e Inteligencia Artificial | Abstracta","article_publisher":"https:\/\/www.facebook.com\/AbstractaChile\/","article_published_time":"2024-04-05T13:22:39+00:00","article_modified_time":"2024-09-26T20:30:50+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024.png","type":"image\/png"}],"author":"Natalie Rodgers, Marketing Team Lead","twitter_card":"summary_large_image","twitter_creator":"@AbstractaChile","twitter_site":"@AbstractaChile","twitter_misc":{"Written by":"Natalie Rodgers, Marketing Team Lead","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#article","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/"},"author":{"name":"Natalie Rodgers, Marketing Team Lead","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/b7978e8cd73ff3ed2dcc7e127499b4cb"},"headline":"Se viene Quality Sense Conf 2024, en Colombia","datePublished":"2024-04-05T13:22:39+00:00","dateModified":"2024-09-26T20:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/"},"wordCount":1792,"commentCount":0,"publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"keywords":["Automatizaci\u00f3n de Pruebas","Calidad de Software","Eventos","Pruebas Basadas en Datos","Pruebas de Accesibilidad","Pruebas de Observabilidad","Pruebas de Performance","Pruebas Funcionales","Quality Sense Conf","Testing de Software"],"articleSection":["Eventos"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/","url":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/","name":"Se viene Quality Sense Conf 2024, en Colombia - Abstracta","isPartOf":{"@id":"https:\/\/es.abstracta.us\/blog\/#website"},"datePublished":"2024-04-05T13:22:39+00:00","dateModified":"2024-09-26T20:30:50+00:00","description":"Nos llena de entusiasmo anunciar la tercera edici\u00f3n de este evento que se est\u00e1 convirtiendo en un cl\u00e1sico de la industria TI. Lo celebraremos en octubre en Medell\u00edn, en busca de seguir aportando al desarrollo y posicionar a Am\u00e9rica Latina como un hub digital en el mundo.","breadcrumb":{"@id":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/es.abstracta.us\/blog\/quality-sense-conf-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.abstracta.us\/blog\/"},{"@type":"ListItem","position":2,"name":"Se viene Quality Sense Conf 2024, en Colombia"}]},{"@type":"WebSite","@id":"https:\/\/es.abstracta.us\/blog\/#website","url":"https:\/\/es.abstracta.us\/blog\/","name":"Abstracta","description":"Recursos, buenas pr\u00e1cticas, tendencias y rese\u00f1as de herramientas de desarrollo de software, testing e Inteligencia Artificial.","publisher":{"@id":"https:\/\/es.abstracta.us\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.abstracta.us\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/es.abstracta.us\/blog\/#organization","name":"Abstracta","url":"https:\/\/es.abstracta.us\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","contentUrl":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2024\/03\/abstracta-logo.png","width":1217,"height":300,"caption":"Abstracta"},"image":{"@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/we_are_abstracta\/","https:\/\/www.linkedin.com\/showcase\/abstracta-chile\/","https:\/\/www.youtube.com\/channel\/UCj4dx2LZCRcgM8GzxYEKYeQ","https:\/\/www.facebook.com\/AbstractaChile\/","https:\/\/twitter.com\/AbstractaChile"]},{"@type":"Person","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/b7978e8cd73ff3ed2dcc7e127499b4cb","name":"Natalie Rodgers, Marketing Team Lead","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/es.abstracta.us\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a23da822367e20ddb98b59d5273eb3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a23da822367e20ddb98b59d5273eb3e?s=96&d=mm&r=g","caption":"Natalie Rodgers, Marketing Team Lead"},"sameAs":["https:\/\/es.abstracta.us\/"],"url":"https:\/\/es.abstracta.us\/blog\/author\/natalie-rodgers\/"}]}},"jetpack_featured_media_url":"https:\/\/es.abstracta.us\/wp-content\/uploads\/2023\/12\/quality-sense-conf-colombia-2024.png","_links":{"self":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/17343"}],"collection":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/comments?post=17343"}],"version-history":[{"count":17,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/17343\/revisions"}],"predecessor-version":[{"id":18577,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/posts\/17343\/revisions\/18577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media\/17330"}],"wp:attachment":[{"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/media?parent=17343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/categories?post=17343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.abstracta.us\/blog\/wp-json\/wp\/v2\/tags?post=17343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}